{"id":48484,"date":"2024-12-23T14:31:45","date_gmt":"2024-12-23T14:31:45","guid":{"rendered":"https:\/\/recambiosecogas.com\/producto\/rail-de-inyeccion-glp-3-cyl-hana-h200-europegas\/"},"modified":"2026-04-15T11:49:47","modified_gmt":"2026-04-15T10:49:47","slug":"rail-de-inyeccion-glp-3-cyl-hana-h200-europegas","status":"publish","type":"product","link":"https:\/\/recambiosecogas.com\/pt-pt\/producto\/rail-de-inyeccion-glp-3-cyl-hana-h200-europegas\/","title":{"rendered":"CARRIL DE INJE\u00c7\u00c3O EUROPEGAS 3 CYL HANA H200 LPG"},"content":{"rendered":"<h1 data-start=\"443\" data-end=\"548\"><strong data-start=\"445\" data-end=\"548\">Trilho de Inje\u00e7\u00e3o de GPL 3 Cilindros Hana H200 tipo B EuropeGas | Precis\u00e3o e Efici\u00eancia para o seu Sistema de GPL<\/strong><\/h1>\n<p data-start=\"550\" data-end=\"1000\">O <strong data-start=\"553\" data-end=\"611\">Cyl Hana H200 Tipo B EuropeGas GPL 3<\/strong> \u00e9 um componente de alta precis\u00e3o concebido para otimizar o funcionamento dos sistemas <strong data-start=\"708\" data-end=\"742\">de g\u00e1s liquefeito de petr\u00f3leo (GPL<\/strong> ) em ve\u00edculos convertidos.<br data-start=\"768\" data-end=\"771\">Gra\u00e7as ao seu design com <strong data-start=\"795\" data-end=\"822\">injetores incorporados<\/strong>, este carril assegura uma distribui\u00e7\u00e3o equilibrada do g\u00e1s para cada cilindro, o que melhora a combust\u00e3o, reduz as emiss\u00f5es e proporciona um desempenho superior ao motor.<\/p>\n<p data-start=\"1002\" data-end=\"1290\">Fabricado pela <strong data-start=\"1016\" data-end=\"1024\">Hana<\/strong>, uma das marcas mais reconhecidas na tecnologia de GPL, este carril destaca-se pela sua fiabilidade, durabilidade e precis\u00e3o na dosagem de combust\u00edvel. Faz tamb\u00e9m parte da gama profissional da EuropeGas, que garante compatibilidade e qualidade certificada. <\/p>\n<hr data-start=\"1292\" data-end=\"1295\">\n<h2 data-start=\"1297\" data-end=\"1370\"><strong data-start=\"1300\" data-end=\"1370\">O que \u00e9 o trilho de inje\u00e7\u00e3o de g\u00e1s LPG 3 do Cyl Hana H200 Tipo B?<\/strong><\/h2>\n<p data-start=\"1372\" data-end=\"1648\">O trilho de inje\u00e7\u00e3o \u00e9 uma parte fundamental do sistema de GLP. A sua principal fun\u00e7\u00e3o \u00e9 gerir com precis\u00e3o a quantidade de g\u00e1s enviada para cada cilindro. <br data-start=\"1532\" data-end=\"1535\"><strong data-start=\"1535\" data-end=\"1553\">Como resultado<\/strong>, o motor recebe uma mistura equilibrada de ar-combust\u00edvel e um funcionamento muito mais suave.<\/p>\n<p data-start=\"1650\" data-end=\"1849\">Este modelo <strong data-start=\"1665\" data-end=\"1680\">de 3 cilindros<\/strong> foi especialmente concebido para motores que requerem pot\u00eancia precisa e constante, ideal para ve\u00edculos urbanos, comerciais ou recentemente convertidos a GPL.<\/p>\n<hr data-start=\"1851\" data-end=\"1854\">\n<h2 data-start=\"1856\" data-end=\"1920\"><strong data-start=\"1859\" data-end=\"1920\">Vantagens do Carril de Inje\u00e7\u00e3o de GLP Cyl Hana H200 Tipo B 3<\/strong><\/h2>\n<h3 data-start=\"1922\" data-end=\"1962\"><strong data-start=\"1926\" data-end=\"1960\">1. Dosagem precisa de GPL<\/strong><\/h3>\n<p data-start=\"1963\" data-end=\"2085\">O sistema distribui a quantidade exata de g\u00e1s para cada cilindro, <strong data-start=\"2028\" data-end=\"2043\">tornando<\/strong> a combust\u00e3o mais limpa e eficiente.<\/p>\n<h3 data-start=\"2087\" data-end=\"2130\"><strong data-start=\"2091\" data-end=\"2128\">2. Melhoria do desempenho do motor<\/strong><\/h3>\n<p data-start=\"2131\" data-end=\"2257\">Gra\u00e7as \u00e0 precis\u00e3o na inje\u00e7\u00e3o, o ve\u00edculo responde melhor \u00e0 acelera\u00e7\u00e3o, oferece maior suavidade e reduz os solavancos.<\/p>\n<h3 data-start=\"2259\" data-end=\"2299\"><strong data-start=\"2263\" data-end=\"2297\">3. Redu\u00e7\u00e3o real de emiss\u00f5es<\/strong><\/h3>\n<p data-start=\"2300\" data-end=\"2388\">Uma mistura equilibrada permite ao motor gerar menos res\u00edduos e gases poluentes.<\/p>\n<h3 data-start=\"2390\" data-end=\"2439\"><strong data-start=\"2394\" data-end=\"2437\">4. Fabrico de alta qualidade pela Hana<\/strong><\/h3>\n<p data-start=\"2440\" data-end=\"2571\"><strong data-start=\"2440\" data-end=\"2452\">Da mesma forma<\/strong>, os materiais utilizados garantem resist\u00eancia, estabilidade t\u00e9rmica e uma longa vida \u00fatil mesmo em uso intensivo.<\/p>\n<h3 data-start=\"2573\" data-end=\"2623\"><strong data-start=\"2577\" data-end=\"2621\">5. Compatibilidade com sistemas EuropeGas<\/strong><\/h3>\n<p data-start=\"2624\" data-end=\"2750\">O carril est\u00e1 preparado para ser facilmente integrado em kits profissionais de GPL, <strong data-start=\"2708\" data-end=\"2720\">facilitando a<\/strong> sua instala\u00e7\u00e3o e calibra\u00e7\u00e3o.<\/p>\n<hr data-start=\"2752\" data-end=\"2755\">\n<h2 data-start=\"2757\" data-end=\"2837\"><strong data-start=\"2760\" data-end=\"2837\">Caracter\u00edsticas t\u00e9cnicas do Carril de Inje\u00e7\u00e3o LPG Tipo B Cyl Hana H200 Tipo B 3<\/strong><\/h2>\n<ul data-start=\"2839\" data-end=\"3141\">\n<li data-start=\"2839\" data-end=\"2878\">\n<p data-start=\"2841\" data-end=\"2878\">Trilho de inje\u00e7\u00e3o para sistemas de GLP<\/p>\n<\/li>\n<li data-start=\"2879\" data-end=\"2906\">\n<p data-start=\"2881\" data-end=\"2906\">Vers\u00e3o <strong data-start=\"2889\" data-end=\"2904\">de 3 cilindros<\/strong><\/p>\n<\/li>\n<li data-start=\"2907\" data-end=\"2950\">\n<p data-start=\"2909\" data-end=\"2950\">Injetores integrados de alta precis\u00e3o<\/p>\n<\/li>\n<li data-start=\"2951\" data-end=\"2981\">\n<p data-start=\"2953\" data-end=\"2981\">Tempo de resposta r\u00e1pido<\/p>\n<\/li>\n<li data-start=\"2982\" data-end=\"3032\">\n<p data-start=\"2984\" data-end=\"3032\">Materiais resistentes \u00e0 temperatura e \u00e0 press\u00e3o<\/p>\n<\/li>\n<li data-start=\"3033\" data-end=\"3074\">\n<p data-start=\"3035\" data-end=\"3074\">Compatibilidade com kits de GPL EuropeGas<\/p>\n<\/li>\n<li data-start=\"3075\" data-end=\"3141\">\n<p data-start=\"3077\" data-end=\"3141\">Ideal para convers\u00f5es modernas e atualiza\u00e7\u00f5es de sistemas<\/p>\n<\/li>\n<\/ul>\n<hr data-start=\"3143\" data-end=\"3146\">\n<h2 data-start=\"3148\" data-end=\"3180\"><strong data-start=\"3151\" data-end=\"3180\">Aplica\u00e7\u00f5es Recomendadas<\/strong><\/h2>\n<p data-start=\"3182\" data-end=\"3248\">O <strong data-start=\"3185\" data-end=\"3233\">trilho de inje\u00e7\u00e3o Cyl Hana H200 Tipo B LPG 3<\/strong> \u00e9 ideal para:<\/p>\n<ul data-start=\"3250\" data-end=\"3496\">\n<li data-start=\"3250\" data-end=\"3295\">\n<p data-start=\"3252\" data-end=\"3295\">Ve\u00edculos recentemente convertidos para GLP<\/p>\n<\/li>\n<li data-start=\"3296\" data-end=\"3333\">\n<p data-start=\"3298\" data-end=\"3333\">Carruagens de passageiros compactas de 3 cilindros<\/p>\n<\/li>\n<li data-start=\"3334\" data-end=\"3388\">\n<p data-start=\"3336\" data-end=\"3388\">Condutores que procuram reduzir o consumo e as emiss\u00f5es<\/p>\n<\/li>\n<li data-start=\"3389\" data-end=\"3423\">\n<p data-start=\"3391\" data-end=\"3423\">EuropeGas e Hana H200 Systems<\/p>\n<\/li>\n<li data-start=\"3424\" data-end=\"3496\">\n<p data-start=\"3426\" data-end=\"3496\">Oficinas profissionais que exigem componentes de qualidade superior<\/p>\n<\/li>\n<\/ul>\n<p data-start=\"3498\" data-end=\"3619\"><strong data-start=\"3498\" data-end=\"3517\">Consequentemente<\/strong>, \u00e9 uma excelente escolha para inje\u00e7\u00e3o precisa e desempenho melhorado em motores a GPL.<\/p>\n<hr data-start=\"3621\" data-end=\"3624\">\n<h2 data-start=\"3626\" data-end=\"3678\"><strong data-start=\"3629\" data-end=\"3678\">Benef\u00edcios diretos da instala\u00e7\u00e3o deste carril de GLP<\/strong><\/h2>\n<ul data-start=\"3680\" data-end=\"3899\">\n<li data-start=\"3680\" data-end=\"3702\">\n<p data-start=\"3682\" data-end=\"3702\">Consumo otimizado<\/p>\n<\/li>\n<li data-start=\"3703\" data-end=\"3728\">\n<p data-start=\"3705\" data-end=\"3728\">Acelera\u00e7\u00e3o mais suave<\/p>\n<\/li>\n<li data-start=\"3729\" data-end=\"3760\">\n<p data-start=\"3731\" data-end=\"3760\">Menos solavancos e vibra\u00e7\u00f5es<\/p>\n<\/li>\n<li data-start=\"3761\" data-end=\"3801\">\n<p data-start=\"3763\" data-end=\"3801\">Redu\u00e7\u00e3o das emiss\u00f5es poluentes<\/p>\n<\/li>\n<li data-start=\"3802\" data-end=\"3835\">\n<p data-start=\"3804\" data-end=\"3835\">Maior durabilidade do sistema<\/p>\n<\/li>\n<li data-start=\"3836\" data-end=\"3899\">\n<p data-start=\"3838\" data-end=\"3899\">Funcionamento mais est\u00e1vel em toda a gama de rota\u00e7\u00f5es<\/p>\n<\/li>\n<\/ul>\n<p data-start=\"3901\" data-end=\"4025\">Em suma, este carril melhora a efici\u00eancia do sistema de GPL e oferece uma experi\u00eancia de condu\u00e7\u00e3o mais confort\u00e1vel e ecol\u00f3gica.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Melhore o desempenho do seu motor com o Cyl Hana H200 3 Injection Rail. Este sistema EuropeGas garante uma distribui\u00e7\u00e3o precisa do GPL, reduzindo as emiss\u00f5es e maximizando a efici\u00eancia. <\/p>\n<p>Torne o seu ve\u00edculo uma op\u00e7\u00e3o mais ecol\u00f3gica e eficiente hoje mesmo!<\/p>\n","protected":false},"featured_media":20729,"comment_status":"open","ping_status":"closed","template":"","meta":{"_uag_custom_page_level_css":""},"product_brand":[],"product_cat":[1703,1591,1597,1601],"product_tag":[],"class_list":{"0":"post-48484","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-europegas-pt-pt","7":"product_cat-injecao","8":"product_cat-injetores-rail","9":"product_cat-rail-riel","11":"first","12":"onbackorder","13":"taxable","14":"shipping-taxable","15":"purchasable","16":"product-type-simple"},"ct_brands":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>CYL HANA H200 LPG INJECTION RAIL %SEP%% Segimon Automoci\u00f3<\/title>\n<meta name=\"description\" content=\"Melhore o desempenho do seu motor com o Cyl Hana H200 LPG 3 Injection Rail. Com injetores incorporados, neste sistema EuropeGas.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/recambiosecogas.com\/pt-pt\/producto\/rail-de-inyeccion-glp-3-cyl-hana-h200-europegas\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CARRIL DE INJE\u00c7\u00c3O EUROPEGAS 3 CYL HANA H200 LPG\" \/>\n<meta property=\"og:description\" content=\"Melhore o desempenho do seu motor com o Cyl Hana H200 LPG 3 Injection Rail. Com injetores incorporados, neste sistema EuropeGas.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/recambiosecogas.com\/pt-pt\/producto\/rail-de-inyeccion-glp-3-cyl-hana-h200-europegas\/\" \/>\n<meta property=\"og:site_name\" content=\"Recambios EcoGas\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/profile.php?id=100062419705358\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-15T10:49:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/recambiosecogas.com\/wp-content\/uploads\/2024\/10\/unnamed-file-1.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"pre\u00e7o\" \/>\n\t<meta name=\"twitter:data1\" content=\"140,00&nbsp;&euro; (Sin IVA: 115,70&nbsp;&euro;)\" \/>\n\t<meta name=\"twitter:label2\" content=\"Disponibilidade\" \/>\n\t<meta name=\"twitter:data2\" content=\"Por encomenda\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/recambiosecogas.com\\\/pt-pt\\\/producto\\\/rail-de-inyeccion-glp-3-cyl-hana-h200-europegas\\\/\",\"url\":\"https:\\\/\\\/recambiosecogas.com\\\/pt-pt\\\/producto\\\/rail-de-inyeccion-glp-3-cyl-hana-h200-europegas\\\/\",\"name\":\"CYL HANA H200 LPG INJECTION RAIL %SEP%% Segimon Automoci\u00f3\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/recambiosecogas.com\\\/pt-pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/recambiosecogas.com\\\/pt-pt\\\/producto\\\/rail-de-inyeccion-glp-3-cyl-hana-h200-europegas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/recambiosecogas.com\\\/pt-pt\\\/producto\\\/rail-de-inyeccion-glp-3-cyl-hana-h200-europegas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/recambiosecogas.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/unnamed-file-1.webp\",\"datePublished\":\"2024-12-23T14:31:45+00:00\",\"dateModified\":\"2026-04-15T10:49:47+00:00\",\"description\":\"Melhore o desempenho do seu motor com o Cyl Hana H200 LPG 3 Injection Rail. Com injetores incorporados, neste sistema EuropeGas.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/recambiosecogas.com\\\/pt-pt\\\/producto\\\/rail-de-inyeccion-glp-3-cyl-hana-h200-europegas\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/recambiosecogas.com\\\/pt-pt\\\/producto\\\/rail-de-inyeccion-glp-3-cyl-hana-h200-europegas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/recambiosecogas.com\\\/pt-pt\\\/producto\\\/rail-de-inyeccion-glp-3-cyl-hana-h200-europegas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/recambiosecogas.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/unnamed-file-1.webp\",\"contentUrl\":\"https:\\\/\\\/recambiosecogas.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/unnamed-file-1.webp\",\"width\":1080,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/recambiosecogas.com\\\/pt-pt\\\/producto\\\/rail-de-inyeccion-glp-3-cyl-hana-h200-europegas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"P\u00e1gina inicial\",\"item\":\"https:\\\/\\\/recambiosecogas.com\\\/pt-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Loja\",\"item\":\"https:\\\/\\\/recambiosecogas.com\\\/pt-pt\\\/tienda\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"CARRIL DE INJE\u00c7\u00c3O EUROPEGAS 3 CYL HANA H200 LPG\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/recambiosecogas.com\\\/pt-pt\\\/#website\",\"url\":\"https:\\\/\\\/recambiosecogas.com\\\/pt-pt\\\/\",\"name\":\"Recambios EcoGas\",\"description\":\"Pe\u00e7as multimarca para sistemas de GPL\\\/GNC\\\/GNL\\\/Hidrog\u00e9nio\",\"publisher\":{\"@id\":\"https:\\\/\\\/recambiosecogas.com\\\/pt-pt\\\/#organization\"},\"alternateName\":\"Recambios Autogas GLP\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/recambiosecogas.com\\\/pt-pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/recambiosecogas.com\\\/pt-pt\\\/#organization\",\"name\":\"Recambios EcoGas\",\"alternateName\":\"Loja de GPL Autog\u00e1s Espanha\",\"url\":\"https:\\\/\\\/recambiosecogas.com\\\/pt-pt\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/recambiosecogas.com\\\/pt-pt\\\/producto\\\/rail-de-inyeccion-glp-3-cyl-hana-h200-europegas\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/recambiosecogas.com\\\/pt-pt\\\/producto\\\/rail-de-inyeccion-glp-3-cyl-hana-h200-europegas\\\/#local-main-organization-logo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/profile.php?id=100062419705358\",\"https:\\\/\\\/www.instagram.com\\\/segimon_automocio\"],\"description\":\"Recambios EcoGas \u2013 Venta y distribuci\u00f3n de sistemas GLP y GNC en Espa\u00f1a y Portugal. Env\u00edos 24 h, soporte t\u00e9cnico a talleres y distribuidores.\",\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/recambiosecogas.com\\\/politicas-privacidad\\\/\"},\"address\":{\"@id\":\"https:\\\/\\\/recambiosecogas.com\\\/pt-pt\\\/producto\\\/rail-de-inyeccion-glp-3-cyl-hana-h200-europegas\\\/#local-main-place-address\"},\"telephone\":[\"616250633\"],\"contactPoint\":{\"@type\":\"ContactPoint\",\"email\":\"export@recambiosecogas.com\"},\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}],\"email\":\"info@recambiosecogas.com\",\"faxNumber\":\"SEGIMON AUTOMOCION SL\",\"vatID\":\"ESB19819861\",\"globalLocationNumber\":\"938 616 339\"},{\"@type\":\"PostalAddress\",\"@id\":\"https:\\\/\\\/recambiosecogas.com\\\/pt-pt\\\/producto\\\/rail-de-inyeccion-glp-3-cyl-hana-h200-europegas\\\/#local-main-place-address\",\"streetAddress\":\"cami antic de vic, 29 (Nave 3), Pol\u00edgono Industrial Congost\",\"addressLocality\":\"CORRO D`AVALL\",\"postalCode\":\"08520\",\"addressRegion\":\"Barcelona\",\"addressCountry\":\"ES\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/recambiosecogas.com\\\/pt-pt\\\/producto\\\/rail-de-inyeccion-glp-3-cyl-hana-h200-europegas\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/recambiosecogas.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/cropped-RECAMBIOS-GLP-png.webp\",\"contentUrl\":\"https:\\\/\\\/recambiosecogas.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/cropped-RECAMBIOS-GLP-png.webp\",\"width\":512,\"height\":512,\"caption\":\"Recambios EcoGas\"}]}<\/script>\n<meta property=\"product:price:amount\" content=\"140.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"backorder\" \/>\n<meta property=\"product:availability\" content=\"available for order\" \/>\n<meta property=\"product:retailer_item_id\" content=\"3100\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<meta name=\"geo.placename\" content=\"CORRO D`AVALL\" \/>\n<meta name=\"geo.region\" content=\"Espanha\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"CYL HANA H200 LPG INJECTION RAIL %SEP%% Segimon Automoci\u00f3","description":"Melhore o desempenho do seu motor com o Cyl Hana H200 LPG 3 Injection Rail. Com injetores incorporados, neste sistema EuropeGas.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/recambiosecogas.com\/pt-pt\/producto\/rail-de-inyeccion-glp-3-cyl-hana-h200-europegas\/","og_locale":"pt_PT","og_type":"article","og_title":"CARRIL DE INJE\u00c7\u00c3O EUROPEGAS 3 CYL HANA H200 LPG","og_description":"Melhore o desempenho do seu motor com o Cyl Hana H200 LPG 3 Injection Rail. Com injetores incorporados, neste sistema EuropeGas.","og_url":"https:\/\/recambiosecogas.com\/pt-pt\/producto\/rail-de-inyeccion-glp-3-cyl-hana-h200-europegas\/","og_site_name":"Recambios EcoGas","article_publisher":"https:\/\/www.facebook.com\/profile.php?id=100062419705358","article_modified_time":"2026-04-15T10:49:47+00:00","og_image":[{"width":1080,"height":1080,"url":"https:\/\/recambiosecogas.com\/wp-content\/uploads\/2024\/10\/unnamed-file-1.webp","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"pre\u00e7o":"140,00&nbsp;&euro; (Sin IVA: 115,70&nbsp;&euro;)","Disponibilidade":"Por encomenda"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/recambiosecogas.com\/pt-pt\/producto\/rail-de-inyeccion-glp-3-cyl-hana-h200-europegas\/","url":"https:\/\/recambiosecogas.com\/pt-pt\/producto\/rail-de-inyeccion-glp-3-cyl-hana-h200-europegas\/","name":"CYL HANA H200 LPG INJECTION RAIL %SEP%% Segimon Automoci\u00f3","isPartOf":{"@id":"https:\/\/recambiosecogas.com\/pt-pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/recambiosecogas.com\/pt-pt\/producto\/rail-de-inyeccion-glp-3-cyl-hana-h200-europegas\/#primaryimage"},"image":{"@id":"https:\/\/recambiosecogas.com\/pt-pt\/producto\/rail-de-inyeccion-glp-3-cyl-hana-h200-europegas\/#primaryimage"},"thumbnailUrl":"https:\/\/recambiosecogas.com\/wp-content\/uploads\/2024\/10\/unnamed-file-1.webp","datePublished":"2024-12-23T14:31:45+00:00","dateModified":"2026-04-15T10:49:47+00:00","description":"Melhore o desempenho do seu motor com o Cyl Hana H200 LPG 3 Injection Rail. Com injetores incorporados, neste sistema EuropeGas.","breadcrumb":{"@id":"https:\/\/recambiosecogas.com\/pt-pt\/producto\/rail-de-inyeccion-glp-3-cyl-hana-h200-europegas\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/recambiosecogas.com\/pt-pt\/producto\/rail-de-inyeccion-glp-3-cyl-hana-h200-europegas\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/recambiosecogas.com\/pt-pt\/producto\/rail-de-inyeccion-glp-3-cyl-hana-h200-europegas\/#primaryimage","url":"https:\/\/recambiosecogas.com\/wp-content\/uploads\/2024\/10\/unnamed-file-1.webp","contentUrl":"https:\/\/recambiosecogas.com\/wp-content\/uploads\/2024\/10\/unnamed-file-1.webp","width":1080,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/recambiosecogas.com\/pt-pt\/producto\/rail-de-inyeccion-glp-3-cyl-hana-h200-europegas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"P\u00e1gina inicial","item":"https:\/\/recambiosecogas.com\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"Loja","item":"https:\/\/recambiosecogas.com\/pt-pt\/tienda\/"},{"@type":"ListItem","position":3,"name":"CARRIL DE INJE\u00c7\u00c3O EUROPEGAS 3 CYL HANA H200 LPG"}]},{"@type":"WebSite","@id":"https:\/\/recambiosecogas.com\/pt-pt\/#website","url":"https:\/\/recambiosecogas.com\/pt-pt\/","name":"Recambios EcoGas","description":"Pe\u00e7as multimarca para sistemas de GPL\/GNC\/GNL\/Hidrog\u00e9nio","publisher":{"@id":"https:\/\/recambiosecogas.com\/pt-pt\/#organization"},"alternateName":"Recambios Autogas GLP","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/recambiosecogas.com\/pt-pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":["Organization","Place"],"@id":"https:\/\/recambiosecogas.com\/pt-pt\/#organization","name":"Recambios EcoGas","alternateName":"Loja de GPL Autog\u00e1s Espanha","url":"https:\/\/recambiosecogas.com\/pt-pt\/","logo":{"@id":"https:\/\/recambiosecogas.com\/pt-pt\/producto\/rail-de-inyeccion-glp-3-cyl-hana-h200-europegas\/#local-main-organization-logo"},"image":{"@id":"https:\/\/recambiosecogas.com\/pt-pt\/producto\/rail-de-inyeccion-glp-3-cyl-hana-h200-europegas\/#local-main-organization-logo"},"sameAs":["https:\/\/www.facebook.com\/profile.php?id=100062419705358","https:\/\/www.instagram.com\/segimon_automocio"],"description":"Recambios EcoGas \u2013 Venta y distribuci\u00f3n de sistemas GLP y GNC en Espa\u00f1a y Portugal. Env\u00edos 24 h, soporte t\u00e9cnico a talleres y distribuidores.","hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/recambiosecogas.com\/politicas-privacidad\/"},"address":{"@id":"https:\/\/recambiosecogas.com\/pt-pt\/producto\/rail-de-inyeccion-glp-3-cyl-hana-h200-europegas\/#local-main-place-address"},"telephone":["616250633"],"contactPoint":{"@type":"ContactPoint","email":"export@recambiosecogas.com"},"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}],"email":"info@recambiosecogas.com","faxNumber":"SEGIMON AUTOMOCION SL","vatID":"ESB19819861","globalLocationNumber":"938 616 339"},{"@type":"PostalAddress","@id":"https:\/\/recambiosecogas.com\/pt-pt\/producto\/rail-de-inyeccion-glp-3-cyl-hana-h200-europegas\/#local-main-place-address","streetAddress":"cami antic de vic, 29 (Nave 3), Pol\u00edgono Industrial Congost","addressLocality":"CORRO D`AVALL","postalCode":"08520","addressRegion":"Barcelona","addressCountry":"ES"},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/recambiosecogas.com\/pt-pt\/producto\/rail-de-inyeccion-glp-3-cyl-hana-h200-europegas\/#local-main-organization-logo","url":"https:\/\/recambiosecogas.com\/wp-content\/uploads\/2024\/11\/cropped-RECAMBIOS-GLP-png.webp","contentUrl":"https:\/\/recambiosecogas.com\/wp-content\/uploads\/2024\/11\/cropped-RECAMBIOS-GLP-png.webp","width":512,"height":512,"caption":"Recambios EcoGas"}]},"product_price_amount":"140.00","product_price_currency":"EUR","og_availability":"backorder","product_availability":"available for order","product_retailer_item_id":"3100","product_condition":"new","geo.placename":"CORRO D`AVALL","geo.region":"Espanha"},"uagb_featured_image_src":{"full":["https:\/\/recambiosecogas.com\/wp-content\/uploads\/2024\/10\/unnamed-file-1.webp",1080,1080,false],"thumbnail":["https:\/\/recambiosecogas.com\/wp-content\/uploads\/2024\/10\/unnamed-file-1-150x150.jpg",150,150,true],"medium":["https:\/\/recambiosecogas.com\/wp-content\/uploads\/2024\/10\/unnamed-file-1-300x300.jpg",300,300,true],"medium_large":["https:\/\/recambiosecogas.com\/wp-content\/uploads\/2024\/10\/unnamed-file-1-768x768.jpg",768,768,true],"large":["https:\/\/recambiosecogas.com\/wp-content\/uploads\/2024\/10\/unnamed-file-1-1000x1000.jpg",1000,1000,true],"1536x1536":["https:\/\/recambiosecogas.com\/wp-content\/uploads\/2024\/10\/unnamed-file-1.webp",1080,1080,false],"2048x2048":["https:\/\/recambiosecogas.com\/wp-content\/uploads\/2024\/10\/unnamed-file-1.webp",1080,1080,false],"woocommerce_archive_thumbnail":["https:\/\/recambiosecogas.com\/wp-content\/uploads\/2024\/10\/unnamed-file-1-1000x1000.webp",1000,1000,true],"woocommerce_thumbnail":["https:\/\/recambiosecogas.com\/wp-content\/uploads\/2024\/10\/unnamed-file-1-300x300.webp",300,300,true],"woocommerce_single":["https:\/\/recambiosecogas.com\/wp-content\/uploads\/2024\/10\/unnamed-file-1-1000x1000.webp",1000,1000,true],"woocommerce_gallery_thumbnail":["https:\/\/recambiosecogas.com\/wp-content\/uploads\/2024\/10\/unnamed-file-1-1000x1000.webp",1000,1000,true],"dgwt-wcas-product-suggestion":["https:\/\/recambiosecogas.com\/wp-content\/uploads\/2024\/10\/unnamed-file-1-64x64.webp",64,64,true]},"uagb_author_info":{"display_name":"Fran - Soporte T\u00e9cnico","author_link":"https:\/\/recambiosecogas.com\/pt-pt\/author\/"},"uagb_comment_info":0,"uagb_excerpt":"Melhore o desempenho do seu motor com o Cyl Hana H200 3 Injection Rail. Este sistema EuropeGas garante uma distribui\u00e7\u00e3o precisa do GPL, reduzindo as emiss\u00f5es e maximizando a efici\u00eancia. Torne o seu ve\u00edculo uma op\u00e7\u00e3o mais ecol\u00f3gica e eficiente hoje mesmo!","_links":{"self":[{"href":"https:\/\/recambiosecogas.com\/pt-pt\/wp-json\/wp\/v2\/product\/48484","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/recambiosecogas.com\/pt-pt\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/recambiosecogas.com\/pt-pt\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/recambiosecogas.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=48484"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/recambiosecogas.com\/pt-pt\/wp-json\/wp\/v2\/media\/20729"}],"wp:attachment":[{"href":"https:\/\/recambiosecogas.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=48484"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/recambiosecogas.com\/pt-pt\/wp-json\/wp\/v2\/product_brand?post=48484"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/recambiosecogas.com\/pt-pt\/wp-json\/wp\/v2\/product_cat?post=48484"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/recambiosecogas.com\/pt-pt\/wp-json\/wp\/v2\/product_tag?post=48484"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}