{"id":7230,"date":"2024-11-20T16:27:16","date_gmt":"2024-11-20T16:27:16","guid":{"rendered":"https:\/\/recambiosecogas.com\/producto\/aeb-mp48-centralita-3-4-cilindros-obd\/"},"modified":"2026-02-23T12:22:01","modified_gmt":"2026-02-23T11:22:01","slug":"aeb-mp48-centralita-3-4-cilindros-obd","status":"publish","type":"product","link":"https:\/\/recambiosecogas.com\/it\/producto\/aeb-mp48-centralita-3-4-cilindros-obd\/","title":{"rendered":"AEB MP48 centralita 3\/4 cilindros (OBD)"},"content":{"rendered":"<h1 data-start=\"174\" data-end=\"213\">AEB MP48 centralita 3\/4 cilindros OBD<\/h1>\n<p data-start=\"215\" data-end=\"535\">La <strong data-start=\"218\" data-end=\"259\">AEB MP48 centralita 3\/4 cilindros OBD<\/strong> es una unidad electr\u00f3nica dise\u00f1ada para la gesti\u00f3n de sistemas Autogas en motores de 3 y 4 cilindros. Esta ECU incorpora comunicaci\u00f3n OBD para la integraci\u00f3n con el sistema de diagn\u00f3stico del veh\u00edculo, permitiendo un control m\u00e1s preciso del funcionamiento del sistema de gas.<\/p>\n<p data-start=\"537\" data-end=\"625\">Est\u00e1 destinada a configuraciones compatibles con plataforma AEB MP48 en versi\u00f3n con OBD.<\/p>\n<hr data-start=\"627\" data-end=\"630\" \/>\n<h2 data-start=\"632\" data-end=\"679\">Unidad electr\u00f3nica MP48 con comunicaci\u00f3n OBD<\/h2>\n<div class=\"TyagGW_tableContainer\">\n<div class=\"group TyagGW_tableWrapper flex flex-col-reverse w-fit\" tabindex=\"-1\">\n<table class=\"w-fit min-w-(--thread-content-width)\" data-start=\"681\" data-end=\"991\">\n<thead data-start=\"681\" data-end=\"709\">\n<tr data-start=\"681\" data-end=\"709\">\n<th class=\"\" data-start=\"681\" data-end=\"698\" data-col-size=\"sm\">Caracter\u00edstica<\/th>\n<th class=\"\" data-start=\"698\" data-end=\"709\" data-col-size=\"sm\">Detalle<\/th>\n<\/tr>\n<\/thead>\n<tbody data-start=\"739\" data-end=\"991\">\n<tr data-start=\"739\" data-end=\"782\">\n<td data-start=\"739\" data-end=\"750\" data-col-size=\"sm\">Producto<\/td>\n<td data-start=\"750\" data-end=\"782\" data-col-size=\"sm\">ECU \/ Centralita electr\u00f3nica<\/td>\n<\/tr>\n<tr data-start=\"783\" data-end=\"810\">\n<td data-start=\"783\" data-end=\"803\" data-col-size=\"sm\">Marca electr\u00f3nica<\/td>\n<td data-start=\"803\" data-end=\"810\" data-col-size=\"sm\">AEB<\/td>\n<\/tr>\n<tr data-start=\"811\" data-end=\"828\">\n<td data-start=\"811\" data-end=\"820\" data-col-size=\"sm\">Modelo<\/td>\n<td data-start=\"820\" data-end=\"828\" data-col-size=\"sm\">MP48<\/td>\n<\/tr>\n<tr data-start=\"829\" data-end=\"863\">\n<td data-start=\"829\" data-end=\"844\" data-col-size=\"sm\">N\u00ba cilindros<\/td>\n<td data-start=\"844\" data-end=\"863\" data-col-size=\"sm\">3 \/ 4 cilindros<\/td>\n<\/tr>\n<tr data-start=\"864\" data-end=\"896\">\n<td data-start=\"864\" data-end=\"879\" data-col-size=\"sm\">Comunicaci\u00f3n<\/td>\n<td data-start=\"879\" data-end=\"896\" data-col-size=\"sm\">OBD integrada<\/td>\n<\/tr>\n<tr data-start=\"897\" data-end=\"939\">\n<td data-start=\"897\" data-end=\"915\" data-col-size=\"sm\">Tipo de sistema<\/td>\n<td data-start=\"915\" data-end=\"939\" data-col-size=\"sm\">Inyecci\u00f3n secuencial<\/td>\n<\/tr>\n<tr data-start=\"940\" data-end=\"961\">\n<td data-start=\"940\" data-end=\"954\" data-col-size=\"sm\">Combustible<\/td>\n<td data-start=\"954\" data-end=\"961\" data-col-size=\"sm\">GLP<\/td>\n<\/tr>\n<tr data-start=\"962\" data-end=\"991\">\n<td data-start=\"962\" data-end=\"976\" data-col-size=\"sm\">Instalaci\u00f3n<\/td>\n<td data-start=\"976\" data-end=\"991\" data-col-size=\"sm\">Profesional<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<\/div>\n<hr data-start=\"993\" data-end=\"996\" \/>\n<h2 data-start=\"998\" data-end=\"1040\">Compatibilidad con sistemas Autogas AEB<\/h2>\n<p data-start=\"1042\" data-end=\"1152\">Compatible con instalaciones que utilicen centralita AEB MP48 versi\u00f3n con OBD para motores de 3 y 4 cilindros.<\/p>\n<p data-start=\"1154\" data-end=\"1254\">Antes de la sustituci\u00f3n, verificar conectores, referencia y compatibilidad con el sistema instalado.<\/p>\n<hr data-start=\"1256\" data-end=\"1259\" \/>\n<h2 data-start=\"1261\" data-end=\"1281\">Ventajas t\u00e9cnicas<\/h2>\n<ul data-start=\"1283\" data-end=\"1482\">\n<li data-start=\"1283\" data-end=\"1326\">\n<p data-start=\"1285\" data-end=\"1326\">Gesti\u00f3n secuencial para 3 y 4 cilindros<\/p>\n<\/li>\n<li data-start=\"1327\" data-end=\"1357\">\n<p data-start=\"1329\" data-end=\"1357\">Comunicaci\u00f3n OBD integrada<\/p>\n<\/li>\n<li data-start=\"1358\" data-end=\"1402\">\n<p data-start=\"1360\" data-end=\"1402\">Integraci\u00f3n con diagn\u00f3stico del veh\u00edculo<\/p>\n<\/li>\n<li data-start=\"1403\" data-end=\"1442\">\n<p data-start=\"1405\" data-end=\"1442\">Recambio t\u00e9cnico para mantenimiento<\/p>\n<\/li>\n<li data-start=\"1443\" data-end=\"1482\">\n<p data-start=\"1445\" data-end=\"1482\">Compatible con sistemas Autogas GLP<\/p>\n<\/li>\n<\/ul>\n<hr data-start=\"1484\" data-end=\"1487\" \/>\n<h2 data-start=\"1489\" data-end=\"1495\">FAQ<\/h2>\n<p data-start=\"1497\" data-end=\"1625\"><strong data-start=\"1497\" data-end=\"1542\">\u00bfPara qu\u00e9 sirve esta centralita MP48 OBD?<\/strong><br data-start=\"1542\" data-end=\"1545\" \/>Gestiona la inyecci\u00f3n de gas en motores de 3 y 4 cilindros con comunicaci\u00f3n OBD.<\/p>\n<p data-start=\"1627\" data-end=\"1756\"><strong data-start=\"1627\" data-end=\"1677\">\u00bfCu\u00e1l es la diferencia con la versi\u00f3n sin OBD?<\/strong><br data-start=\"1677\" data-end=\"1680\" \/>Esta versi\u00f3n permite integraci\u00f3n con el sistema de diagn\u00f3stico del veh\u00edculo.<\/p>\n<p data-start=\"1758\" data-end=\"1843\"><strong data-start=\"1758\" data-end=\"1792\">\u00bfEs v\u00e1lida para 5\/6 cilindros?<\/strong><br data-start=\"1792\" data-end=\"1795\" \/>No, est\u00e1 destinada a motores de 3 o 4 cilindros.<\/p>\n<p data-start=\"1845\" data-end=\"1923\"><strong data-start=\"1845\" data-end=\"1872\">\u00bfRequiere programaci\u00f3n?<\/strong><br data-start=\"1872\" data-end=\"1875\" \/>S\u00ed, debe configurarse por t\u00e9cnico especializado.<\/p>\n","protected":false},"excerpt":{"rendered":"<p data-start=\"2349\" data-end=\"2460\">AEB MP48 centralita 3\/4 cilindros con comunicaci\u00f3n OBD integrada. Unidad electr\u00f3nica para sistemas Autogas GLP.<\/p>\n","protected":false},"featured_media":10191,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_uag_custom_page_level_css":""},"product_brand":[959],"product_cat":[480,297],"product_tag":[],"class_list":{"0":"post-7230","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-aeb-electronics","7":"product_cat-centralitas-electronicas","8":"product_cat-electronica","10":"first","11":"onbackorder","12":"taxable","13":"shipping-taxable","14":"purchasable","15":"product-type-simple"},"ct_brands":[{"id":959,"name":"AEB ELECTRONICS","slug":"aeb-electronics"}],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>AEB MP48 centralita 3\/4 cilindros (OBD) | Recambios EcoGas | Sistemas GLP y GNC<\/title>\n<meta name=\"description\" content=\"AEB MP48 centralita 3\/4 cilindros con OBD integrada. ECU para sistemas Autogas GLP en motores de 3 y 4 cilindros.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/recambiosecogas.com\/it\/producto\/aeb-mp48-centralita-3-4-cilindros-obd\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"AEB MP48 centralita 3\/4 cilindros (OBD)\" \/>\n<meta property=\"og:description\" content=\"AEB MP48 centralita 3\/4 cilindros con OBD integrada. ECU para sistemas Autogas GLP en motores de 3 y 4 cilindros.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/recambiosecogas.com\/it\/producto\/aeb-mp48-centralita-3-4-cilindros-obd\/\" \/>\n<meta property=\"og:site_name\" content=\"Recambios EcoGas\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/profile.php?id=100062419705358\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-23T11:22:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/recambiosecogas.com\/wp-content\/uploads\/2024\/11\/AEB-MP48-centralita-3-4-cilindros-OBD-png.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Prezzo\" \/>\n\t<meta name=\"twitter:data1\" content=\"214,80&nbsp;&euro; (Sin IVA: 177,52&nbsp;&euro;)\" \/>\n\t<meta name=\"twitter:label2\" content=\"Disponibilit\u00e0\" \/>\n\t<meta name=\"twitter:data2\" content=\"Su ordinazione\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/recambiosecogas.com\\\/it\\\/producto\\\/aeb-mp48-centralita-3-4-cilindros-obd\\\/\",\"url\":\"https:\\\/\\\/recambiosecogas.com\\\/it\\\/producto\\\/aeb-mp48-centralita-3-4-cilindros-obd\\\/\",\"name\":\"AEB MP48 centralita 3\\\/4 cilindros (OBD) | Recambios EcoGas | Sistemas GLP y GNC\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/recambiosecogas.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/recambiosecogas.com\\\/it\\\/producto\\\/aeb-mp48-centralita-3-4-cilindros-obd\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/recambiosecogas.com\\\/it\\\/producto\\\/aeb-mp48-centralita-3-4-cilindros-obd\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/recambiosecogas.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/AEB-MP48-centralita-3-4-cilindros-OBD-png.webp\",\"datePublished\":\"2024-11-20T16:27:16+00:00\",\"dateModified\":\"2026-02-23T11:22:01+00:00\",\"description\":\"AEB MP48 centralita 3\\\/4 cilindros con OBD integrada. ECU para sistemas Autogas GLP en motores de 3 y 4 cilindros.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/recambiosecogas.com\\\/it\\\/producto\\\/aeb-mp48-centralita-3-4-cilindros-obd\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/recambiosecogas.com\\\/it\\\/producto\\\/aeb-mp48-centralita-3-4-cilindros-obd\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/recambiosecogas.com\\\/it\\\/producto\\\/aeb-mp48-centralita-3-4-cilindros-obd\\\/#primaryimage\",\"url\":\"https:\\\/\\\/recambiosecogas.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/AEB-MP48-centralita-3-4-cilindros-OBD-png.webp\",\"contentUrl\":\"https:\\\/\\\/recambiosecogas.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/AEB-MP48-centralita-3-4-cilindros-OBD-png.webp\",\"width\":1000,\"height\":1000},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/recambiosecogas.com\\\/it\\\/producto\\\/aeb-mp48-centralita-3-4-cilindros-obd\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/recambiosecogas.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Negozio\",\"item\":\"https:\\\/\\\/recambiosecogas.com\\\/it\\\/?page_id=46382\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"AEB MP48 centralita 3\\\/4 cilindros (OBD)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/recambiosecogas.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/recambiosecogas.com\\\/it\\\/\",\"name\":\"Recambios EcoGas\",\"description\":\"Recambios Multimarca para sistemas de GLP\\\/GNC\\\/GNL\\\/Hidr\u00f3geno\",\"publisher\":{\"@id\":\"https:\\\/\\\/recambiosecogas.com\\\/it\\\/#organization\"},\"alternateName\":\"Recambios Autogas GLP\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/recambiosecogas.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/recambiosecogas.com\\\/it\\\/#organization\",\"name\":\"Recambios EcoGas\",\"alternateName\":\"Tienda Online GLP Espa\u00f1a\",\"url\":\"https:\\\/\\\/recambiosecogas.com\\\/it\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/recambiosecogas.com\\\/it\\\/producto\\\/aeb-mp48-centralita-3-4-cilindros-obd\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/recambiosecogas.com\\\/it\\\/producto\\\/aeb-mp48-centralita-3-4-cilindros-obd\\\/#local-main-organization-logo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/profile.php?id=100062419705358\",\"https:\\\/\\\/www.instagram.com\\\/segimon_automocio\"],\"description\":\"Recambios EcoGas \u2013 Venta y distribuci\u00f3n de sistemas GLP y GNC en Espa\u00f1a y Portugal. Env\u00edos 24 h, soporte t\u00e9cnico a talleres y distribuidores.\",\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/recambiosecogas.com\\\/politicas-privacidad\\\/\"},\"address\":{\"@id\":\"https:\\\/\\\/recambiosecogas.com\\\/it\\\/producto\\\/aeb-mp48-centralita-3-4-cilindros-obd\\\/#local-main-place-address\"},\"telephone\":[\"616250633\"],\"contactPoint\":{\"@type\":\"ContactPoint\",\"email\":\"export@recambiosecogas.com\"},\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}],\"email\":\"info@recambiosecogas.com\",\"faxNumber\":\"SEGIMON AUTOMOCION SL\",\"vatID\":\"ESB19819861\",\"globalLocationNumber\":\"938 616 339\"},{\"@type\":\"PostalAddress\",\"@id\":\"https:\\\/\\\/recambiosecogas.com\\\/it\\\/producto\\\/aeb-mp48-centralita-3-4-cilindros-obd\\\/#local-main-place-address\",\"streetAddress\":\"cami antic de vic, 29 (Nave 3), Pol\u00edgono Industrial Congost\",\"addressLocality\":\"CORRO D`AVALL\",\"postalCode\":\"08520\",\"addressRegion\":\"Barcelona\",\"addressCountry\":\"ES\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/recambiosecogas.com\\\/it\\\/producto\\\/aeb-mp48-centralita-3-4-cilindros-obd\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/recambiosecogas.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/cropped-RECAMBIOS-GLP-png.webp\",\"contentUrl\":\"https:\\\/\\\/recambiosecogas.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/cropped-RECAMBIOS-GLP-png.webp\",\"width\":512,\"height\":512,\"caption\":\"Recambios EcoGas\"}]}<\/script>\n<meta property=\"product:brand\" content=\"AEB ELECTRONICS\" \/>\n<meta property=\"product:price:amount\" content=\"214.80\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"backorder\" \/>\n<meta property=\"product:availability\" content=\"available for order\" \/>\n<meta property=\"product:retailer_item_id\" content=\"107841A\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<meta name=\"geo.placename\" content=\"CORRO D`AVALL\" \/>\n<meta name=\"geo.region\" content=\"Spagna\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"AEB MP48 centralita 3\/4 cilindros (OBD) | Recambios EcoGas | Sistemas GLP y GNC","description":"AEB MP48 centralita 3\/4 cilindros con OBD integrada. ECU para sistemas Autogas GLP en motores de 3 y 4 cilindros.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/recambiosecogas.com\/it\/producto\/aeb-mp48-centralita-3-4-cilindros-obd\/","og_locale":"it_IT","og_type":"article","og_title":"AEB MP48 centralita 3\/4 cilindros (OBD)","og_description":"AEB MP48 centralita 3\/4 cilindros con OBD integrada. ECU para sistemas Autogas GLP en motores de 3 y 4 cilindros.","og_url":"https:\/\/recambiosecogas.com\/it\/producto\/aeb-mp48-centralita-3-4-cilindros-obd\/","og_site_name":"Recambios EcoGas","article_publisher":"https:\/\/www.facebook.com\/profile.php?id=100062419705358","article_modified_time":"2026-02-23T11:22:01+00:00","og_image":[{"width":1000,"height":1000,"url":"https:\/\/recambiosecogas.com\/wp-content\/uploads\/2024\/11\/AEB-MP48-centralita-3-4-cilindros-OBD-png.webp","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Prezzo":"214,80&nbsp;&euro; (Sin IVA: 177,52&nbsp;&euro;)","Disponibilit\u00e0":"Su ordinazione"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/recambiosecogas.com\/it\/producto\/aeb-mp48-centralita-3-4-cilindros-obd\/","url":"https:\/\/recambiosecogas.com\/it\/producto\/aeb-mp48-centralita-3-4-cilindros-obd\/","name":"AEB MP48 centralita 3\/4 cilindros (OBD) | Recambios EcoGas | Sistemas GLP y GNC","isPartOf":{"@id":"https:\/\/recambiosecogas.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/recambiosecogas.com\/it\/producto\/aeb-mp48-centralita-3-4-cilindros-obd\/#primaryimage"},"image":{"@id":"https:\/\/recambiosecogas.com\/it\/producto\/aeb-mp48-centralita-3-4-cilindros-obd\/#primaryimage"},"thumbnailUrl":"https:\/\/recambiosecogas.com\/wp-content\/uploads\/2024\/11\/AEB-MP48-centralita-3-4-cilindros-OBD-png.webp","datePublished":"2024-11-20T16:27:16+00:00","dateModified":"2026-02-23T11:22:01+00:00","description":"AEB MP48 centralita 3\/4 cilindros con OBD integrada. ECU para sistemas Autogas GLP en motores de 3 y 4 cilindros.","breadcrumb":{"@id":"https:\/\/recambiosecogas.com\/it\/producto\/aeb-mp48-centralita-3-4-cilindros-obd\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/recambiosecogas.com\/it\/producto\/aeb-mp48-centralita-3-4-cilindros-obd\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/recambiosecogas.com\/it\/producto\/aeb-mp48-centralita-3-4-cilindros-obd\/#primaryimage","url":"https:\/\/recambiosecogas.com\/wp-content\/uploads\/2024\/11\/AEB-MP48-centralita-3-4-cilindros-OBD-png.webp","contentUrl":"https:\/\/recambiosecogas.com\/wp-content\/uploads\/2024\/11\/AEB-MP48-centralita-3-4-cilindros-OBD-png.webp","width":1000,"height":1000},{"@type":"BreadcrumbList","@id":"https:\/\/recambiosecogas.com\/it\/producto\/aeb-mp48-centralita-3-4-cilindros-obd\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/recambiosecogas.com\/it\/"},{"@type":"ListItem","position":2,"name":"Negozio","item":"https:\/\/recambiosecogas.com\/it\/?page_id=46382"},{"@type":"ListItem","position":3,"name":"AEB MP48 centralita 3\/4 cilindros (OBD)"}]},{"@type":"WebSite","@id":"https:\/\/recambiosecogas.com\/it\/#website","url":"https:\/\/recambiosecogas.com\/it\/","name":"Recambios EcoGas","description":"Recambios Multimarca para sistemas de GLP\/GNC\/GNL\/Hidr\u00f3geno","publisher":{"@id":"https:\/\/recambiosecogas.com\/it\/#organization"},"alternateName":"Recambios Autogas GLP","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/recambiosecogas.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/recambiosecogas.com\/it\/#organization","name":"Recambios EcoGas","alternateName":"Tienda Online GLP Espa\u00f1a","url":"https:\/\/recambiosecogas.com\/it\/","logo":{"@id":"https:\/\/recambiosecogas.com\/it\/producto\/aeb-mp48-centralita-3-4-cilindros-obd\/#local-main-organization-logo"},"image":{"@id":"https:\/\/recambiosecogas.com\/it\/producto\/aeb-mp48-centralita-3-4-cilindros-obd\/#local-main-organization-logo"},"sameAs":["https:\/\/www.facebook.com\/profile.php?id=100062419705358","https:\/\/www.instagram.com\/segimon_automocio"],"description":"Recambios EcoGas \u2013 Venta y distribuci\u00f3n de sistemas GLP y GNC en Espa\u00f1a y Portugal. Env\u00edos 24 h, soporte t\u00e9cnico a talleres y distribuidores.","hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/recambiosecogas.com\/politicas-privacidad\/"},"address":{"@id":"https:\/\/recambiosecogas.com\/it\/producto\/aeb-mp48-centralita-3-4-cilindros-obd\/#local-main-place-address"},"telephone":["616250633"],"contactPoint":{"@type":"ContactPoint","email":"export@recambiosecogas.com"},"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}],"email":"info@recambiosecogas.com","faxNumber":"SEGIMON AUTOMOCION SL","vatID":"ESB19819861","globalLocationNumber":"938 616 339"},{"@type":"PostalAddress","@id":"https:\/\/recambiosecogas.com\/it\/producto\/aeb-mp48-centralita-3-4-cilindros-obd\/#local-main-place-address","streetAddress":"cami antic de vic, 29 (Nave 3), Pol\u00edgono Industrial Congost","addressLocality":"CORRO D`AVALL","postalCode":"08520","addressRegion":"Barcelona","addressCountry":"ES"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/recambiosecogas.com\/it\/producto\/aeb-mp48-centralita-3-4-cilindros-obd\/#local-main-organization-logo","url":"https:\/\/recambiosecogas.com\/wp-content\/uploads\/2024\/11\/cropped-RECAMBIOS-GLP-png.webp","contentUrl":"https:\/\/recambiosecogas.com\/wp-content\/uploads\/2024\/11\/cropped-RECAMBIOS-GLP-png.webp","width":512,"height":512,"caption":"Recambios EcoGas"}]},"product_brand":"AEB ELECTRONICS","product_price_amount":"214.80","product_price_currency":"EUR","og_availability":"backorder","product_availability":"available for order","product_retailer_item_id":"107841A","product_condition":"new","geo.placename":"CORRO D`AVALL","geo.region":"Spagna"},"uagb_featured_image_src":{"full":["https:\/\/recambiosecogas.com\/wp-content\/uploads\/2024\/11\/AEB-MP48-centralita-3-4-cilindros-OBD-png.webp",1000,1000,false],"thumbnail":["https:\/\/recambiosecogas.com\/wp-content\/uploads\/2024\/11\/AEB-MP48-centralita-3-4-cilindros-OBD-150x150.webp",150,150,true],"medium":["https:\/\/recambiosecogas.com\/wp-content\/uploads\/2024\/11\/AEB-MP48-centralita-3-4-cilindros-OBD-300x300.webp",300,300,true],"medium_large":["https:\/\/recambiosecogas.com\/wp-content\/uploads\/2024\/11\/AEB-MP48-centralita-3-4-cilindros-OBD-768x768.webp",768,768,true],"large":["https:\/\/recambiosecogas.com\/wp-content\/uploads\/2024\/11\/AEB-MP48-centralita-3-4-cilindros-OBD-png.webp",1000,1000,false],"1536x1536":["https:\/\/recambiosecogas.com\/wp-content\/uploads\/2024\/11\/AEB-MP48-centralita-3-4-cilindros-OBD-png.webp",1000,1000,false],"2048x2048":["https:\/\/recambiosecogas.com\/wp-content\/uploads\/2024\/11\/AEB-MP48-centralita-3-4-cilindros-OBD-png.webp",1000,1000,false],"woocommerce_archive_thumbnail":["https:\/\/recambiosecogas.com\/wp-content\/uploads\/2024\/11\/AEB-MP48-centralita-3-4-cilindros-OBD-png.webp",1000,1000,false],"woocommerce_thumbnail":["https:\/\/recambiosecogas.com\/wp-content\/uploads\/2024\/11\/AEB-MP48-centralita-3-4-cilindros-OBD-png-300x300.webp",300,300,true],"woocommerce_single":["https:\/\/recambiosecogas.com\/wp-content\/uploads\/2024\/11\/AEB-MP48-centralita-3-4-cilindros-OBD-png.webp",1000,1000,false],"woocommerce_gallery_thumbnail":["https:\/\/recambiosecogas.com\/wp-content\/uploads\/2024\/11\/AEB-MP48-centralita-3-4-cilindros-OBD-png.webp",1000,1000,false],"dgwt-wcas-product-suggestion":["https:\/\/recambiosecogas.com\/wp-content\/uploads\/2024\/11\/AEB-MP48-centralita-3-4-cilindros-OBD-png-64x64.webp",64,64,true]},"uagb_author_info":{"display_name":"Fran - Soporte T\u00e9cnico","author_link":"https:\/\/recambiosecogas.com\/it\/author\/"},"uagb_comment_info":0,"uagb_excerpt":"AEB MP48 centralita 3\/4 cilindros con comunicaci\u00f3n OBD integrada. Unidad electr\u00f3nica para sistemas Autogas GLP.","_links":{"self":[{"href":"https:\/\/recambiosecogas.com\/it\/wp-json\/wp\/v2\/product\/7230","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/recambiosecogas.com\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/recambiosecogas.com\/it\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/recambiosecogas.com\/it\/wp-json\/wp\/v2\/comments?post=7230"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/recambiosecogas.com\/it\/wp-json\/wp\/v2\/media\/10191"}],"wp:attachment":[{"href":"https:\/\/recambiosecogas.com\/it\/wp-json\/wp\/v2\/media?parent=7230"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/recambiosecogas.com\/it\/wp-json\/wp\/v2\/product_brand?post=7230"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/recambiosecogas.com\/it\/wp-json\/wp\/v2\/product_cat?post=7230"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/recambiosecogas.com\/it\/wp-json\/wp\/v2\/product_tag?post=7230"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}