{"id":48686,"date":"2025-02-21T11:26:12","date_gmt":"2025-02-21T11:26:12","guid":{"rendered":"https:\/\/recambiosecogas.com\/producto\/landi-renzo-med-oem-inyector-glp-gnv-solo-para-fiat-con-conector-mta-nueva-version-de-12-agujeros\/"},"modified":"2026-04-15T11:51:41","modified_gmt":"2026-04-15T10:51:41","slug":"landi-renzo-med-oem-inyector-glp-gnv-solo-para-fiat-con-conector-mta-nueva-version-de-12-agujeros","status":"publish","type":"product","link":"https:\/\/recambiosecogas.com\/it\/producto\/landi-renzo-med-oem-inyector-glp-gnv-solo-para-fiat-con-conector-mta-nueva-version-de-12-agujeros\/","title":{"rendered":"Iniettori Landi Renzo MED OEM LPG\/CNG \u2013 Nuova Versione 12 Fori"},"content":{"rendered":"<h3 data-start=\"138\" data-end=\"266\"><strong data-start=\"141\" data-end=\"266\">Landi Renzo MED OEM LPG\/CNG Iniettori \u2013 Nuova Versione 12 Fori | Per FIAT \u2013 MTA Connector | Rif. OPEL 821010 \/ 9271859<\/strong><\/h3>\n<p data-start=\"268\" data-end=\"529\">Iniettori Landi Renzo MED OEM LPG\/CNG \u2013 Nuova Versione 12 Fori progettati per <strong data-start=\"338\" data-end=\"372\">l&#8217;iniezione diretta di GPL o GNC<\/strong> nei sistemi autogas. Questo componente \u00e8 compatibile con i veicoli del gruppo FIAT che integrano sistemi Landi Renzo gi\u00e0 in fabbrica e utilizzano <strong data-start=\"512\" data-end=\"528\">il connettore MTA<\/strong>. <\/p>\n<p data-start=\"531\" data-end=\"914\">Questa nuova versione ha <strong data-start=\"561\" data-end=\"590\">12 fori di iniezione<\/strong>, che permettono una <strong data-start=\"611\" data-end=\"646\">nebulizzazione pi\u00f9 fine e precisa<\/strong> del gas, migliorando le prestazioni del motore, riducendo i consumi e ottimizzando le emissioni. \u00c8 un&#8217;evoluzione dei modelli precedenti con 4 fori e <strong data-start=\"803\" data-end=\"843\">non \u00e8 intercambiabile individualmente<\/strong>: <strong data-start=\"845\" data-end=\"913\">tutti gli iniettori devono essere sostituiti con lo stesso nuovo modello<\/strong>. <\/p>\n<p data-start=\"916\" data-end=\"1037\">L&#8217;identificazione di ciascun iniettore si fa facilmente dal <strong data-start=\"980\" data-end=\"1009\">colore del tappo superiore<\/strong>, secondo il seguente codice:<\/p>\n<div class=\"pointer-events-none relative left-[50%] flex w-[100cqw] translate-x-[-50%] justify-center *:pointer-events-auto\">\n<div class=\"tableContainer horzScrollShadows\">\n<table class=\"min-w-full\" data-start=\"1039\" data-end=\"1385\">\n<thead data-start=\"1039\" data-end=\"1095\">\n<tr data-start=\"1039\" data-end=\"1095\">\n<th data-start=\"1039\" data-end=\"1067\"><strong data-start=\"1041\" data-end=\"1066\">Antique (4 buchi)<\/strong><\/th>\n<th data-start=\"1067\" data-end=\"1095\"><strong data-start=\"1069\" data-end=\"1093\">Nuovo (12 buche)<\/strong><\/th>\n<\/tr>\n<\/thead>\n<tbody data-start=\"1154\" data-end=\"1385\">\n<tr data-start=\"1154\" data-end=\"1211\">\n<td class=\"max-w-[calc(var(--thread-content-max-width)*2\/3)]\" data-start=\"1154\" data-end=\"1182\">Giallo<\/td>\n<td class=\"max-w-[calc(var(--thread-content-max-width)*2\/3)]\" data-start=\"1182\" data-end=\"1211\">Grigio<\/td>\n<\/tr>\n<tr data-start=\"1212\" data-end=\"1269\">\n<td class=\"max-w-[calc(var(--thread-content-max-width)*2\/3)]\" data-start=\"1212\" data-end=\"1240\">Verde<\/td>\n<td class=\"max-w-[calc(var(--thread-content-max-width)*2\/3)]\" data-start=\"1240\" data-end=\"1269\">Arancione<\/td>\n<\/tr>\n<tr data-start=\"1270\" data-end=\"1327\">\n<td class=\"max-w-[calc(var(--thread-content-max-width)*2\/3)]\" data-start=\"1270\" data-end=\"1298\">Nero<\/td>\n<td class=\"max-w-[calc(var(--thread-content-max-width)*2\/3)]\" data-start=\"1298\" data-end=\"1327\">Blu<\/td>\n<\/tr>\n<tr data-start=\"1328\" data-end=\"1385\">\n<td class=\"max-w-[calc(var(--thread-content-max-width)*2\/3)]\" data-start=\"1328\" data-end=\"1356\">Bianco<\/td>\n<td class=\"max-w-[calc(var(--thread-content-max-width)*2\/3)]\" data-start=\"1356\" data-end=\"1385\">Violet<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<\/div>\n<p data-start=\"1387\" data-end=\"1615\">Questo iniettore \u00e8 approvato secondo le normative ECE R67 per l&#8217;uso su veicoli alimentati a gas liquefatto (GPL) o gas naturale (GNC), offrendo un elevato standard di sicurezza, qualit\u00e0 e affidabilit\u00e0 in condizioni di uso intensivo.<\/p>\n<p data-start=\"1617\" data-end=\"1823\"><strong data-start=\"1617\" data-end=\"1632\">Importante:<\/strong> Questo iniettore MED deve essere installato sulla <strong data-start=\"1676\" data-end=\"1702\">corrispondente rotaia<\/strong>, anch&#8217;essa approvata secondo le normative vigenti. Non compatibile con le versioni pi\u00f9 vecchie senza una sostituzione completa del set. <\/p>\n<hr class=\"\" data-start=\"1825\" data-end=\"1828\">\n<h4 data-start=\"1830\" data-end=\"1882\"><strong data-start=\"1834\" data-end=\"1882\">Caratteristiche tecniche \u2013 tabella di tipo Excel<\/strong><\/h4>\n<div class=\"pointer-events-none relative left-[50%] flex w-[100cqw] translate-x-[-50%] justify-center *:pointer-events-auto\">\n<div class=\"tableContainer horzScrollShadows\">\n<table class=\"min-w-full\" data-start=\"1884\" data-end=\"3129\">\n<thead data-start=\"1884\" data-end=\"1979\">\n<tr data-start=\"1884\" data-end=\"1979\">\n<th data-start=\"1884\" data-end=\"1915\"><strong data-start=\"1886\" data-end=\"1904\">Specifiche<\/strong><\/th>\n<th data-start=\"1915\" data-end=\"1979\"><strong data-start=\"1917\" data-end=\"1928\">Dettagli<\/strong><\/th>\n<\/tr>\n<\/thead>\n<tbody data-start=\"2076\" data-end=\"3129\">\n<tr data-start=\"2076\" data-end=\"2170\">\n<td class=\"max-w-[calc(var(--thread-content-max-width)*2\/3)]\" data-start=\"2076\" data-end=\"2107\"><strong data-start=\"2078\" data-end=\"2098\">Tipo di iniettore<\/strong><\/td>\n<td class=\"max-w-[calc(var(--thread-content-max-width)*2\/3)] min-w-[calc(var(--thread-content-max-width)\/3)]\" data-start=\"2107\" data-end=\"2170\">LPG \/ CNG \u2013 Iniezione sequenziale multipunto<\/td>\n<\/tr>\n<tr data-start=\"2171\" data-end=\"2266\">\n<td class=\"max-w-[calc(var(--thread-content-max-width)*2\/3)]\" data-start=\"2171\" data-end=\"2202\"><strong data-start=\"2173\" data-end=\"2195\">Marchio \/ Produttore<\/strong><\/td>\n<td class=\"max-w-[calc(var(--thread-content-max-width)*2\/3)]\" data-start=\"2202\" data-end=\"2266\">Landi Renzo MED (OEM)<\/td>\n<\/tr>\n<tr data-start=\"2267\" data-end=\"2362\">\n<td class=\"max-w-[calc(var(--thread-content-max-width)*2\/3)]\" data-start=\"2267\" data-end=\"2298\"><strong data-start=\"2269\" data-end=\"2287\">Compatibilit\u00e0<\/strong><\/td>\n<td class=\"max-w-[calc(var(--thread-content-max-width)*2\/3)]\" data-start=\"2298\" data-end=\"2362\">Sistemi FIAT con connettore MTA<\/td>\n<\/tr>\n<tr data-start=\"2363\" data-end=\"2458\">\n<td class=\"max-w-[calc(var(--thread-content-max-width)*2\/3)]\" data-start=\"2363\" data-end=\"2394\"><strong data-start=\"2365\" data-end=\"2384\">Riferimento OPEL<\/strong><\/td>\n<td class=\"max-w-[calc(var(--thread-content-max-width)*2\/3)]\" data-start=\"2394\" data-end=\"2458\">821010 \/ 9271859<\/td>\n<\/tr>\n<tr data-start=\"2459\" data-end=\"2554\">\n<td class=\"max-w-[calc(var(--thread-content-max-width)*2\/3)]\" data-start=\"2459\" data-end=\"2490\"><strong data-start=\"2461\" data-end=\"2473\">Connettore<\/strong><\/td>\n<td class=\"max-w-[calc(var(--thread-content-max-width)*2\/3)]\" data-start=\"2490\" data-end=\"2554\">MTA<\/td>\n<\/tr>\n<tr data-start=\"2555\" data-end=\"2649\">\n<td class=\"max-w-[calc(var(--thread-content-max-width)*2\/3)]\" data-start=\"2555\" data-end=\"2586\"><strong data-start=\"2557\" data-end=\"2568\">Versione<\/strong><\/td>\n<td class=\"max-w-[calc(var(--thread-content-max-width)*2\/3)]\" data-start=\"2586\" data-end=\"2649\">Nuovo \u2013 12 fori di iniezione<\/td>\n<\/tr>\n<tr data-start=\"2650\" data-end=\"2745\">\n<td class=\"max-w-[calc(var(--thread-content-max-width)*2\/3)]\" data-start=\"2650\" data-end=\"2681\"><strong data-start=\"2652\" data-end=\"2674\">Sostituzione completa<\/strong><\/td>\n<td class=\"max-w-[calc(var(--thread-content-max-width)*2\/3)] min-w-[calc(var(--thread-content-max-width)\/3)]\" data-start=\"2681\" data-end=\"2745\">S\u00ec, tutti gli iniettori nell&#8217;assemblaggio devono essere sostituiti<\/td>\n<\/tr>\n<tr data-start=\"2746\" data-end=\"2841\">\n<td class=\"max-w-[calc(var(--thread-content-max-width)*2\/3)]\" data-start=\"2746\" data-end=\"2777\"><strong data-start=\"2748\" data-end=\"2775\">Colori (nuova versione)<\/strong><\/td>\n<td class=\"max-w-[calc(var(--thread-content-max-width)*2\/3)]\" data-start=\"2777\" data-end=\"2841\">Grigio, Arancione, Blu, Viola<\/td>\n<\/tr>\n<tr data-start=\"2842\" data-end=\"2937\">\n<td class=\"max-w-[calc(var(--thread-content-max-width)*2\/3)]\" data-start=\"2842\" data-end=\"2873\"><strong data-start=\"2844\" data-end=\"2857\">Regolamenti<\/strong><\/td>\n<td class=\"max-w-[calc(var(--thread-content-max-width)*2\/3)] min-w-[calc(var(--thread-content-max-width)\/3)]\" data-start=\"2873\" data-end=\"2937\">ECE R67 \u2013 Iniettore: E13 67R-010234 \/ Rail: E13 67R-010233<\/td>\n<\/tr>\n<tr data-start=\"2938\" data-end=\"3033\">\n<td class=\"max-w-[calc(var(--thread-content-max-width)*2\/3)]\" data-start=\"2938\" data-end=\"2969\"><strong data-start=\"2940\" data-end=\"2958\">Uso compatibile<\/strong><\/td>\n<td class=\"max-w-[calc(var(--thread-content-max-width)*2\/3)]\" data-start=\"2969\" data-end=\"3033\">Sistemi a GPL e GNC<\/td>\n<\/tr>\n<tr data-start=\"3034\" data-end=\"3129\">\n<td class=\"max-w-[calc(var(--thread-content-max-width)*2\/3)]\" data-start=\"3034\" data-end=\"3065\"><strong data-start=\"3036\" data-end=\"3047\">Montaggio<\/strong><\/td>\n<td class=\"max-w-[calc(var(--thread-content-max-width)*2\/3)]\" data-start=\"3065\" data-end=\"3129\">In rotaie a 2, 3 o 4 cilindri<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><a href=\"https:\/\/recambiosecogas.com\/it\/categoria-producto\/inyectores-menu\/inyectores-rail\/\">Il nostro catalogo di iniettori.<\/a><\/p>\n<p><a href=\"https:\/\/segimonautomocio.com\/\">Cambia i tuoi iniettori nel nostro laboratorio specializzato.<\/a><\/p>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Landi Renzo MED OEM LPG\/CNG Iniettori \u2013 Nuova Versione 12 Fori | Per FIAT \u2013 MTA Connector | Rif. OPEL 821010 \/ 9271859 Iniettori Landi Renzo MED OEM LPG\/CNG \u2013 Nuova Versione 12 Fori progettati per l&#8217;iniezione diretta di GPL o GNC nei sistemi autogas. Questo componente \u00e8 compatibile con i veicoli del gruppo FIAT [&hellip;]<\/p>\n","protected":false},"featured_media":48692,"comment_status":"open","ping_status":"closed","template":"","meta":{"_uag_custom_page_level_css":""},"product_brand":[],"product_cat":[2121,2122,2154,2125,2212],"product_tag":[2127],"class_list":["post-48686","product","type-product","status-publish","has-post-thumbnail","product_cat-inyectores-menu","product_cat-inyectores-rail","product_cat-inyectores-individuales","product_cat-recambios-oem","product_cat-recambios-oem-fiat","product_tag-oem","first","instock","taxable","shipping-taxable","purchasable","product-type-variable"],"ct_brands":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.9 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Iniettori Landi Renzo MED OEM LPG\/CNG \u2013 Nuova Versione 12 Fori | Recambios EcoGas | Sistemas GLP y GNC<\/title>\n<meta name=\"description\" content=\"Landi Renzo MED MEM LPG\/CNG Iniettore per FIAT. Versione a 12 fori con connettore MTA. Rif. OPEL 821010\/9271859. E13 approvato.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/recambiosecogas.com\/it\/producto\/landi-renzo-med-oem-inyector-glp-gnv-solo-para-fiat-con-conector-mta-nueva-version-de-12-agujeros\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Iniettori Landi Renzo MED OEM LPG\/CNG \u2013 Nuova Versione 12 Fori\" \/>\n<meta property=\"og:description\" content=\"Landi Renzo MED MEM LPG\/CNG Iniettore per FIAT. Versione a 12 fori con connettore MTA. Rif. OPEL 821010\/9271859. E13 approvato.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/recambiosecogas.com\/it\/producto\/landi-renzo-med-oem-inyector-glp-gnv-solo-para-fiat-con-conector-mta-nueva-version-de-12-agujeros\/\" \/>\n<meta property=\"og:site_name\" content=\"Recambios EcoGas\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/profile.php?id=100062419705358\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-15T10:51:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/recambiosecogas.com\/wp-content\/uploads\/2025\/02\/Landi-Renzo-MED-OEM-inyector-GI25-65-AZUL-GLP-GNV-solo-para-FIAT-con-conector-MTA-nueva-version-de-12-agujeros-png.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Disponibilit\u00e0\" \/>\n\t<meta name=\"twitter:data1\" content=\"In stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/recambiosecogas.com\\\/it\\\/producto\\\/landi-renzo-med-oem-inyector-glp-gnv-solo-para-fiat-con-conector-mta-nueva-version-de-12-agujeros\\\/\",\"url\":\"https:\\\/\\\/recambiosecogas.com\\\/it\\\/producto\\\/landi-renzo-med-oem-inyector-glp-gnv-solo-para-fiat-con-conector-mta-nueva-version-de-12-agujeros\\\/\",\"name\":\"Iniettori Landi Renzo MED OEM LPG\\\/CNG \u2013 Nuova Versione 12 Fori | Recambios EcoGas | Sistemas GLP y GNC\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/recambiosecogas.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/recambiosecogas.com\\\/it\\\/producto\\\/landi-renzo-med-oem-inyector-glp-gnv-solo-para-fiat-con-conector-mta-nueva-version-de-12-agujeros\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/recambiosecogas.com\\\/it\\\/producto\\\/landi-renzo-med-oem-inyector-glp-gnv-solo-para-fiat-con-conector-mta-nueva-version-de-12-agujeros\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/recambiosecogas.com\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/Landi-Renzo-MED-OEM-inyector-GI25-65-AZUL-GLP-GNV-solo-para-FIAT-con-conector-MTA-nueva-version-de-12-agujeros-png.webp\",\"datePublished\":\"2025-02-21T11:26:12+00:00\",\"dateModified\":\"2026-04-15T10:51:41+00:00\",\"description\":\"Landi Renzo MED MEM LPG\\\/CNG Iniettore per FIAT. Versione a 12 fori con connettore MTA. Rif. OPEL 821010\\\/9271859. E13 approvato.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/recambiosecogas.com\\\/it\\\/producto\\\/landi-renzo-med-oem-inyector-glp-gnv-solo-para-fiat-con-conector-mta-nueva-version-de-12-agujeros\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/recambiosecogas.com\\\/it\\\/producto\\\/landi-renzo-med-oem-inyector-glp-gnv-solo-para-fiat-con-conector-mta-nueva-version-de-12-agujeros\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/recambiosecogas.com\\\/it\\\/producto\\\/landi-renzo-med-oem-inyector-glp-gnv-solo-para-fiat-con-conector-mta-nueva-version-de-12-agujeros\\\/#primaryimage\",\"url\":\"https:\\\/\\\/recambiosecogas.com\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/Landi-Renzo-MED-OEM-inyector-GI25-65-AZUL-GLP-GNV-solo-para-FIAT-con-conector-MTA-nueva-version-de-12-agujeros-png.webp\",\"contentUrl\":\"https:\\\/\\\/recambiosecogas.com\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/Landi-Renzo-MED-OEM-inyector-GI25-65-AZUL-GLP-GNV-solo-para-FIAT-con-conector-MTA-nueva-version-de-12-agujeros-png.webp\",\"width\":1000,\"height\":1000},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/recambiosecogas.com\\\/it\\\/producto\\\/landi-renzo-med-oem-inyector-glp-gnv-solo-para-fiat-con-conector-mta-nueva-version-de-12-agujeros\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Copertina\",\"item\":\"https:\\\/\\\/recambiosecogas.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Negozio\",\"item\":\"https:\\\/\\\/recambiosecogas.com\\\/it\\\/?page_id=46382\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Iniettori Landi Renzo MED OEM LPG\\\/CNG \u2013 Nuova Versione 12 Fori\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/recambiosecogas.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/recambiosecogas.com\\\/it\\\/\",\"name\":\"Recambios EcoGas\",\"description\":\"Recambios Multimarca para sistemas de GLP\\\/GNC\\\/GNL\\\/Hidr\u00f3geno\",\"publisher\":{\"@id\":\"https:\\\/\\\/recambiosecogas.com\\\/it\\\/#organization\"},\"alternateName\":\"Recambios Autogas GLP\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/recambiosecogas.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/recambiosecogas.com\\\/it\\\/#organization\",\"name\":\"Recambios EcoGas\",\"alternateName\":\"Tienda Online GLP Espa\u00f1a\",\"url\":\"https:\\\/\\\/recambiosecogas.com\\\/it\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/recambiosecogas.com\\\/it\\\/producto\\\/landi-renzo-med-oem-inyector-glp-gnv-solo-para-fiat-con-conector-mta-nueva-version-de-12-agujeros\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/recambiosecogas.com\\\/it\\\/producto\\\/landi-renzo-med-oem-inyector-glp-gnv-solo-para-fiat-con-conector-mta-nueva-version-de-12-agujeros\\\/#local-main-organization-logo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/profile.php?id=100062419705358\",\"https:\\\/\\\/www.instagram.com\\\/segimon_automocio\"],\"description\":\"Recambios EcoGas \u2013 Venta y distribuci\u00f3n de sistemas GLP y GNC en Espa\u00f1a y Portugal. Env\u00edos 24 h, soporte t\u00e9cnico a talleres y distribuidores.\",\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/recambiosecogas.com\\\/politicas-privacidad\\\/\"},\"address\":{\"@id\":\"https:\\\/\\\/recambiosecogas.com\\\/it\\\/producto\\\/landi-renzo-med-oem-inyector-glp-gnv-solo-para-fiat-con-conector-mta-nueva-version-de-12-agujeros\\\/#local-main-place-address\"},\"telephone\":[\"616250633\"],\"contactPoint\":{\"@type\":\"ContactPoint\",\"email\":\"export@recambiosecogas.com\"},\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}],\"email\":\"info@recambiosecogas.com\",\"faxNumber\":\"SEGIMON AUTOMOCION SL\",\"vatID\":\"ESB19819861\",\"globalLocationNumber\":\"938 616 339\"},{\"@type\":\"PostalAddress\",\"@id\":\"https:\\\/\\\/recambiosecogas.com\\\/it\\\/producto\\\/landi-renzo-med-oem-inyector-glp-gnv-solo-para-fiat-con-conector-mta-nueva-version-de-12-agujeros\\\/#local-main-place-address\",\"streetAddress\":\"cami antic de vic, 29 (Nave 3), Pol\u00edgono Industrial Congost\",\"addressLocality\":\"CORRO D`AVALL\",\"postalCode\":\"08520\",\"addressRegion\":\"Barcelona\",\"addressCountry\":\"ES\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/recambiosecogas.com\\\/it\\\/producto\\\/landi-renzo-med-oem-inyector-glp-gnv-solo-para-fiat-con-conector-mta-nueva-version-de-12-agujeros\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/recambiosecogas.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/cropped-RECAMBIOS-GLP-png.webp\",\"contentUrl\":\"https:\\\/\\\/recambiosecogas.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/cropped-RECAMBIOS-GLP-png.webp\",\"width\":512,\"height\":512,\"caption\":\"Recambios EcoGas\"}]}<\/script>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"105196\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<meta name=\"geo.placename\" content=\"CORRO D`AVALL\" \/>\n<meta name=\"geo.region\" content=\"Spagna\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Iniettori Landi Renzo MED OEM LPG\/CNG \u2013 Nuova Versione 12 Fori | Recambios EcoGas | Sistemas GLP y GNC","description":"Landi Renzo MED MEM LPG\/CNG Iniettore per FIAT. Versione a 12 fori con connettore MTA. Rif. OPEL 821010\/9271859. E13 approvato.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/recambiosecogas.com\/it\/producto\/landi-renzo-med-oem-inyector-glp-gnv-solo-para-fiat-con-conector-mta-nueva-version-de-12-agujeros\/","og_locale":"it_IT","og_type":"article","og_title":"Iniettori Landi Renzo MED OEM LPG\/CNG \u2013 Nuova Versione 12 Fori","og_description":"Landi Renzo MED MEM LPG\/CNG Iniettore per FIAT. Versione a 12 fori con connettore MTA. Rif. OPEL 821010\/9271859. E13 approvato.","og_url":"https:\/\/recambiosecogas.com\/it\/producto\/landi-renzo-med-oem-inyector-glp-gnv-solo-para-fiat-con-conector-mta-nueva-version-de-12-agujeros\/","og_site_name":"Recambios EcoGas","article_publisher":"https:\/\/www.facebook.com\/profile.php?id=100062419705358","article_modified_time":"2026-04-15T10:51:41+00:00","og_image":[{"width":1000,"height":1000,"url":"https:\/\/recambiosecogas.com\/wp-content\/uploads\/2025\/02\/Landi-Renzo-MED-OEM-inyector-GI25-65-AZUL-GLP-GNV-solo-para-FIAT-con-conector-MTA-nueva-version-de-12-agujeros-png.webp","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Disponibilit\u00e0":"In stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/recambiosecogas.com\/it\/producto\/landi-renzo-med-oem-inyector-glp-gnv-solo-para-fiat-con-conector-mta-nueva-version-de-12-agujeros\/","url":"https:\/\/recambiosecogas.com\/it\/producto\/landi-renzo-med-oem-inyector-glp-gnv-solo-para-fiat-con-conector-mta-nueva-version-de-12-agujeros\/","name":"Iniettori Landi Renzo MED OEM LPG\/CNG \u2013 Nuova Versione 12 Fori | Recambios EcoGas | Sistemas GLP y GNC","isPartOf":{"@id":"https:\/\/recambiosecogas.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/recambiosecogas.com\/it\/producto\/landi-renzo-med-oem-inyector-glp-gnv-solo-para-fiat-con-conector-mta-nueva-version-de-12-agujeros\/#primaryimage"},"image":{"@id":"https:\/\/recambiosecogas.com\/it\/producto\/landi-renzo-med-oem-inyector-glp-gnv-solo-para-fiat-con-conector-mta-nueva-version-de-12-agujeros\/#primaryimage"},"thumbnailUrl":"https:\/\/recambiosecogas.com\/wp-content\/uploads\/2025\/02\/Landi-Renzo-MED-OEM-inyector-GI25-65-AZUL-GLP-GNV-solo-para-FIAT-con-conector-MTA-nueva-version-de-12-agujeros-png.webp","datePublished":"2025-02-21T11:26:12+00:00","dateModified":"2026-04-15T10:51:41+00:00","description":"Landi Renzo MED MEM LPG\/CNG Iniettore per FIAT. Versione a 12 fori con connettore MTA. Rif. OPEL 821010\/9271859. E13 approvato.","breadcrumb":{"@id":"https:\/\/recambiosecogas.com\/it\/producto\/landi-renzo-med-oem-inyector-glp-gnv-solo-para-fiat-con-conector-mta-nueva-version-de-12-agujeros\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/recambiosecogas.com\/it\/producto\/landi-renzo-med-oem-inyector-glp-gnv-solo-para-fiat-con-conector-mta-nueva-version-de-12-agujeros\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/recambiosecogas.com\/it\/producto\/landi-renzo-med-oem-inyector-glp-gnv-solo-para-fiat-con-conector-mta-nueva-version-de-12-agujeros\/#primaryimage","url":"https:\/\/recambiosecogas.com\/wp-content\/uploads\/2025\/02\/Landi-Renzo-MED-OEM-inyector-GI25-65-AZUL-GLP-GNV-solo-para-FIAT-con-conector-MTA-nueva-version-de-12-agujeros-png.webp","contentUrl":"https:\/\/recambiosecogas.com\/wp-content\/uploads\/2025\/02\/Landi-Renzo-MED-OEM-inyector-GI25-65-AZUL-GLP-GNV-solo-para-FIAT-con-conector-MTA-nueva-version-de-12-agujeros-png.webp","width":1000,"height":1000},{"@type":"BreadcrumbList","@id":"https:\/\/recambiosecogas.com\/it\/producto\/landi-renzo-med-oem-inyector-glp-gnv-solo-para-fiat-con-conector-mta-nueva-version-de-12-agujeros\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Copertina","item":"https:\/\/recambiosecogas.com\/it\/"},{"@type":"ListItem","position":2,"name":"Negozio","item":"https:\/\/recambiosecogas.com\/it\/?page_id=46382"},{"@type":"ListItem","position":3,"name":"Iniettori Landi Renzo MED OEM LPG\/CNG \u2013 Nuova Versione 12 Fori"}]},{"@type":"WebSite","@id":"https:\/\/recambiosecogas.com\/it\/#website","url":"https:\/\/recambiosecogas.com\/it\/","name":"Recambios EcoGas","description":"Recambios Multimarca para sistemas de GLP\/GNC\/GNL\/Hidr\u00f3geno","publisher":{"@id":"https:\/\/recambiosecogas.com\/it\/#organization"},"alternateName":"Recambios Autogas GLP","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/recambiosecogas.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/recambiosecogas.com\/it\/#organization","name":"Recambios EcoGas","alternateName":"Tienda Online GLP Espa\u00f1a","url":"https:\/\/recambiosecogas.com\/it\/","logo":{"@id":"https:\/\/recambiosecogas.com\/it\/producto\/landi-renzo-med-oem-inyector-glp-gnv-solo-para-fiat-con-conector-mta-nueva-version-de-12-agujeros\/#local-main-organization-logo"},"image":{"@id":"https:\/\/recambiosecogas.com\/it\/producto\/landi-renzo-med-oem-inyector-glp-gnv-solo-para-fiat-con-conector-mta-nueva-version-de-12-agujeros\/#local-main-organization-logo"},"sameAs":["https:\/\/www.facebook.com\/profile.php?id=100062419705358","https:\/\/www.instagram.com\/segimon_automocio"],"description":"Recambios EcoGas \u2013 Venta y distribuci\u00f3n de sistemas GLP y GNC en Espa\u00f1a y Portugal. Env\u00edos 24 h, soporte t\u00e9cnico a talleres y distribuidores.","hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/recambiosecogas.com\/politicas-privacidad\/"},"address":{"@id":"https:\/\/recambiosecogas.com\/it\/producto\/landi-renzo-med-oem-inyector-glp-gnv-solo-para-fiat-con-conector-mta-nueva-version-de-12-agujeros\/#local-main-place-address"},"telephone":["616250633"],"contactPoint":{"@type":"ContactPoint","email":"export@recambiosecogas.com"},"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}],"email":"info@recambiosecogas.com","faxNumber":"SEGIMON AUTOMOCION SL","vatID":"ESB19819861","globalLocationNumber":"938 616 339"},{"@type":"PostalAddress","@id":"https:\/\/recambiosecogas.com\/it\/producto\/landi-renzo-med-oem-inyector-glp-gnv-solo-para-fiat-con-conector-mta-nueva-version-de-12-agujeros\/#local-main-place-address","streetAddress":"cami antic de vic, 29 (Nave 3), Pol\u00edgono Industrial Congost","addressLocality":"CORRO D`AVALL","postalCode":"08520","addressRegion":"Barcelona","addressCountry":"ES"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/recambiosecogas.com\/it\/producto\/landi-renzo-med-oem-inyector-glp-gnv-solo-para-fiat-con-conector-mta-nueva-version-de-12-agujeros\/#local-main-organization-logo","url":"https:\/\/recambiosecogas.com\/wp-content\/uploads\/2024\/11\/cropped-RECAMBIOS-GLP-png.webp","contentUrl":"https:\/\/recambiosecogas.com\/wp-content\/uploads\/2024\/11\/cropped-RECAMBIOS-GLP-png.webp","width":512,"height":512,"caption":"Recambios EcoGas"}]},"og_availability":"instock","product_availability":"instock","product_retailer_item_id":"105196","product_condition":"new","geo.placename":"CORRO D`AVALL","geo.region":"Spagna"},"uagb_featured_image_src":{"full":["https:\/\/recambiosecogas.com\/wp-content\/uploads\/2025\/02\/Landi-Renzo-MED-OEM-inyector-GI25-65-AZUL-GLP-GNV-solo-para-FIAT-con-conector-MTA-nueva-version-de-12-agujeros-png.webp",1000,1000,false],"thumbnail":["https:\/\/recambiosecogas.com\/wp-content\/uploads\/2025\/02\/Landi-Renzo-MED-OEM-inyector-GI25-65-AZUL-GLP-GNV-solo-para-FIAT-con-conector-MTA-nueva-version-de-12-agujeros-150x150.webp",150,150,true],"medium":["https:\/\/recambiosecogas.com\/wp-content\/uploads\/2025\/02\/Landi-Renzo-MED-OEM-inyector-GI25-65-AZUL-GLP-GNV-solo-para-FIAT-con-conector-MTA-nueva-version-de-12-agujeros-300x300.webp",300,300,true],"medium_large":["https:\/\/recambiosecogas.com\/wp-content\/uploads\/2025\/02\/Landi-Renzo-MED-OEM-inyector-GI25-65-AZUL-GLP-GNV-solo-para-FIAT-con-conector-MTA-nueva-version-de-12-agujeros-768x768.webp",768,768,true],"large":["https:\/\/recambiosecogas.com\/wp-content\/uploads\/2025\/02\/Landi-Renzo-MED-OEM-inyector-GI25-65-AZUL-GLP-GNV-solo-para-FIAT-con-conector-MTA-nueva-version-de-12-agujeros-png.webp",1000,1000,false],"1536x1536":["https:\/\/recambiosecogas.com\/wp-content\/uploads\/2025\/02\/Landi-Renzo-MED-OEM-inyector-GI25-65-AZUL-GLP-GNV-solo-para-FIAT-con-conector-MTA-nueva-version-de-12-agujeros-png.webp",1000,1000,false],"2048x2048":["https:\/\/recambiosecogas.com\/wp-content\/uploads\/2025\/02\/Landi-Renzo-MED-OEM-inyector-GI25-65-AZUL-GLP-GNV-solo-para-FIAT-con-conector-MTA-nueva-version-de-12-agujeros-png.webp",1000,1000,false],"woocommerce_archive_thumbnail":["https:\/\/recambiosecogas.com\/wp-content\/uploads\/2025\/02\/Landi-Renzo-MED-OEM-inyector-GI25-65-AZUL-GLP-GNV-solo-para-FIAT-con-conector-MTA-nueva-version-de-12-agujeros-png.webp",1000,1000,false],"woocommerce_thumbnail":["https:\/\/recambiosecogas.com\/wp-content\/uploads\/2025\/02\/Landi-Renzo-MED-OEM-inyector-GI25-65-AZUL-GLP-GNV-solo-para-FIAT-con-conector-MTA-nueva-version-de-12-agujeros-300x300.webp",300,300,true],"woocommerce_single":["https:\/\/recambiosecogas.com\/wp-content\/uploads\/2025\/02\/Landi-Renzo-MED-OEM-inyector-GI25-65-AZUL-GLP-GNV-solo-para-FIAT-con-conector-MTA-nueva-version-de-12-agujeros-png.webp",1000,1000,false],"woocommerce_gallery_thumbnail":["https:\/\/recambiosecogas.com\/wp-content\/uploads\/2025\/02\/Landi-Renzo-MED-OEM-inyector-GI25-65-AZUL-GLP-GNV-solo-para-FIAT-con-conector-MTA-nueva-version-de-12-agujeros-png.webp",1000,1000,false],"dgwt-wcas-product-suggestion":["https:\/\/recambiosecogas.com\/wp-content\/uploads\/2025\/02\/Landi-Renzo-MED-OEM-inyector-GI25-65-AZUL-GLP-GNV-solo-para-FIAT-con-conector-MTA-nueva-version-de-12-agujeros-64x64.webp",64,64,true]},"uagb_author_info":{"display_name":"Fran - Soporte T\u00e9cnico","author_link":"https:\/\/recambiosecogas.com\/it\/author\/"},"uagb_comment_info":0,"uagb_excerpt":"Landi Renzo MED OEM LPG\/CNG Iniettori \u2013 Nuova Versione 12 Fori | Per FIAT \u2013 MTA Connector | Rif. OPEL 821010 \/ 9271859 Iniettori Landi Renzo MED OEM LPG\/CNG \u2013 Nuova Versione 12 Fori progettati per l&#8217;iniezione diretta di GPL o GNC nei sistemi autogas. Questo componente \u00e8 compatibile con i veicoli del gruppo FIAT&hellip;","_links":{"self":[{"href":"https:\/\/recambiosecogas.com\/it\/wp-json\/wp\/v2\/product\/48686","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/recambiosecogas.com\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/recambiosecogas.com\/it\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/recambiosecogas.com\/it\/wp-json\/wp\/v2\/comments?post=48686"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/recambiosecogas.com\/it\/wp-json\/wp\/v2\/media\/48692"}],"wp:attachment":[{"href":"https:\/\/recambiosecogas.com\/it\/wp-json\/wp\/v2\/media?parent=48686"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/recambiosecogas.com\/it\/wp-json\/wp\/v2\/product_brand?post=48686"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/recambiosecogas.com\/it\/wp-json\/wp\/v2\/product_cat?post=48686"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/recambiosecogas.com\/it\/wp-json\/wp\/v2\/product_tag?post=48686"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}